{"id":3300,"date":"2014-04-18T15:51:42","date_gmt":"2014-04-18T15:51:42","guid":{"rendered":"http:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster11.jpg"},"modified":"2014-04-18T15:51:42","modified_gmt":"2014-04-18T15:51:42","slug":"poster1-2","status":"inherit","type":"attachment","link":"https:\/\/art.bradley.edu\/will\/2014\/04\/18\/poster-series-challenge\/poster1-2\/","title":{"rendered":"poster1"},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"class_list":["post-3300","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster11.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"191\" height=\"300\" src=\"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster11-191x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster11-191x300.jpg 191w, https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster11.jpg 653w\" sizes=\"auto, 100vw\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Jay Ryan\/Par a Dice<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":653,"height":1024,"file":"2014\/04\/poster11.jpg","sizes":{"thumbnail":{"file":"poster11-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster11-150x150.jpg"},"medium":{"file":"poster11-191x300.jpg","width":191,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster11-191x300.jpg"},"large":{"file":"poster11-653x1024.jpg","width":653,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster11-653x1024.jpg"},"full":{"file":"poster11.jpg","width":653,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster11.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":3270,"source_url":"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster11.jpg","filename":"poster11.jpg","filesize":173051,"_links":{"self":[{"href":"https:\/\/art.bradley.edu\/will\/wp-json\/wp\/v2\/media\/3300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/art.bradley.edu\/will\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/art.bradley.edu\/will\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/art.bradley.edu\/will\/wp-json\/wp\/v2\/users\/10"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":3270,"href":"https:\/\/art.bradley.edu\/will\/wp-json\/wp\/v2\/posts\/3270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}