{"id":3303,"date":"2014-04-18T15:51:45","date_gmt":"2014-04-18T15:51:45","guid":{"rendered":"http:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster4.jpg"},"modified":"2014-04-18T15:51:45","modified_gmt":"2014-04-18T15:51:45","slug":"poster4-2","status":"inherit","type":"attachment","link":"https:\/\/art.bradley.edu\/will\/2014\/04\/18\/poster-series-challenge\/poster4-2\/","title":{"rendered":"poster4"},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":[],"class_list":["post-3303","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster4.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"196\" height=\"300\" src=\"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster4-196x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster4-196x300.jpg 196w, https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster4-671x1024.jpg 671w, https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster4.jpg 672w\" sizes=\"auto, 100vw\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":672,"height":1024,"file":"2014\/04\/poster4.jpg","sizes":{"thumbnail":{"file":"poster4-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster4-150x150.jpg"},"medium":{"file":"poster4-196x300.jpg","width":196,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster4-196x300.jpg"},"large":{"file":"poster4-671x1024.jpg","width":671,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster4-671x1024.jpg"},"full":{"file":"poster4.jpg","width":672,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster4.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":3270,"source_url":"https:\/\/art.bradley.edu\/will\/files\/2014\/04\/poster4.jpg","filename":"poster4.jpg","filesize":224064,"_links":{"self":[{"href":"https:\/\/art.bradley.edu\/will\/wp-json\/wp\/v2\/media\/3303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/art.bradley.edu\/will\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/art.bradley.edu\/will\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/art.bradley.edu\/will\/wp-json\/wp\/v2\/users\/10"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":3270,"href":"https:\/\/art.bradley.edu\/will\/wp-json\/wp\/v2\/posts\/3270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}